{"id":28412,"date":"2024-06-27T12:17:36","date_gmt":"2024-06-27T15:17:36","guid":{"rendered":"https:\/\/www.aurum.com.br\/blog\/clt-comentado\/art-235-a-a-235-h-clt\/"},"modified":"2025-05-19T15:14:02","modified_gmt":"2025-05-19T18:14:02","slug":"art-235-a-a-235-h-clt","status":"publish","type":"clt-comentado","link":"https:\/\/www.aurum.com.br\/blog\/clt-comentado\/art-235-a-a-235-h-clt\/","title":{"rendered":"Se\u00e7\u00e3o IV-A \u2013 Do Servi\u00e7o do Motorista Profissional Empregado"},"content":{"rendered":"<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-A.<\/strong> Os preceitos especiais desta Se\u00e7\u00e3o aplicam-se ao motorista profissional empregado:<\/p>\n<p>I &#8211; de transporte rodovi\u00e1rio coletivo de passageiros;<br \/>\nII &#8211; de transporte rodovi\u00e1rio de cargas.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-B.<\/strong> S\u00e3o deveres do motorista profissional empregado:<\/p>\n<p>I &#8211; estar atento \u00e0s condi\u00e7\u00f5es de seguran\u00e7a do ve\u00edculo;<br \/>\nII &#8211; conduzir o ve\u00edculo com per\u00edcia, prud\u00eancia, zelo e com observ\u00e2ncia aos princ\u00edpios de dire\u00e7\u00e3o defensiva;<br \/>\nIII &#8211; respeitar a legisla\u00e7\u00e3o de tr\u00e2nsito e, em especial, as normas relativas ao tempo de dire\u00e7\u00e3o e de descanso controlado e registrado na forma do previsto no art. 67-E da Lei no 9.503, de 23 de setembro de 1997 &#8211; C\u00f3digo de Tr\u00e2nsito Brasileiro;<br \/>\nIV &#8211; zelar pela carga transportada e pelo ve\u00edculo;<br \/>\nV &#8211; colocar-se \u00e0 disposi\u00e7\u00e3o dos \u00f3rg\u00e3os p\u00fablicos de fiscaliza\u00e7\u00e3o na via p\u00fablica;<br \/>\nVI &#8211; (VETADO);<br \/>\nVII &#8211; submeter-se a exames toxicol\u00f3gicos com janela de detec\u00e7\u00e3o m\u00ednima de 90 (noventa) dias e a programa de controle de uso de droga e de bebida alco\u00f3lica, institu\u00eddo pelo empregador, com sua ampla ci\u00eancia, pelo menos uma vez a cada 2 (dois) anos e 6 (seis) meses, podendo ser utilizado para esse fim o exame obrigat\u00f3rio previsto na Lei no 9.503, de 23 de setembro de 1997 &#8211; C\u00f3digo de Tr\u00e2nsito Brasileiro, desde que realizado nos \u00faltimos 60 (sessenta) dias.<\/p>\n<p>Par\u00e1grafo \u00fanico. A recusa do empregado em submeter-se ao teste ou ao programa de controle de uso de droga e de bebida alco\u00f3lica previstos no inciso VII ser\u00e1 considerada infra\u00e7\u00e3o disciplinar, pass\u00edvel de penaliza\u00e7\u00e3o nos termos da lei.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-C.<\/strong> A jornada di\u00e1ria de trabalho do motorista profissional ser\u00e1 de 8 (oito) horas, admitindo-se a sua prorroga\u00e7\u00e3o por at\u00e9 2 (duas) horas extraordin\u00e1rias ou, mediante previs\u00e3o em conven\u00e7\u00e3o ou acordo coletivo, por at\u00e9 4 (quatro) horas extraordin\u00e1rias.<\/p>\n<p>\u00a7 1\u00ba Ser\u00e1 considerado como trabalho efetivo o tempo em que o motorista empregado estiver \u00e0 disposi\u00e7\u00e3o do empregador, exclu\u00eddos os intervalos para refei\u00e7\u00e3o, repouso e descanso e o tempo de espera.<\/p>\n<p>\u00a7 2\u00ba Ser\u00e1 assegurado ao motorista profissional empregado intervalo m\u00ednimo de 1 (uma) hora para refei\u00e7\u00e3o, podendo esse per\u00edodo coincidir com o tempo de parada obrigat\u00f3ria na condu\u00e7\u00e3o do ve\u00edculo estabelecido pela Lei no 9.503, de 23 de setembro de 1997 &#8211; C\u00f3digo de Tr\u00e2nsito Brasileiro, exceto quando se tratar do motorista profissional enquadrado no \u00a7 5o do art. 71 desta Consolida\u00e7\u00e3o.<\/p>\n<p>\u00a7 3\u00ba Dentro do per\u00edodo de 24 (vinte e quatro) horas, s\u00e3o asseguradas 11 (onze) horas de descanso, sendo facultados o seu fracionamento e a coincid\u00eancia com os per\u00edodos de parada obrigat\u00f3ria na condu\u00e7\u00e3o do ve\u00edculo estabelecida pela Lei no 9.503, de 23 de setembro de 1997 &#8211; C\u00f3digo de Tr\u00e2nsito Brasileiro, garantidos o m\u00ednimo de 8 (oito) horas ininterruptas no primeiro per\u00edodo e o gozo do remanescente dentro das 16 (dezesseis) horas seguintes ao fim do primeiro per\u00edodo.<\/p>\n<p>\u00a7 4\u00ba Nas viagens de longa dist\u00e2ncia, assim consideradas aquelas em que o motorista profissional empregado permanece fora da base da empresa, matriz ou filial e de sua resid\u00eancia por mais de 24 (vinte e quatro) horas, o repouso di\u00e1rio pode ser feito no ve\u00edculo ou em alojamento do empregador, do contratante do transporte, do embarcador ou do destinat\u00e1rio ou em outro local que ofere\u00e7a condi\u00e7\u00f5es adequadas.<\/p>\n<p>\u00a7 5\u00ba As horas consideradas extraordin\u00e1rias ser\u00e3o pagas com o acr\u00e9scimo estabelecido na Constitui\u00e7\u00e3o Federal ou compensadas na forma do \u00a7 2o do art. 59 desta Consolida\u00e7\u00e3o.<\/p>\n<p>\u00a7 6\u00ba \u00c0 hora de trabalho noturno aplica-se o disposto no art. 73 desta Consolida\u00e7\u00e3o.<\/p>\n<p>\u00a7 7\u00ba (VETADO).<\/p>\n<p>\u00a7 8\u00ba S\u00e3o considerados tempo de espera as horas em que o motorista profissional empregado ficar aguardando carga ou descarga do ve\u00edculo nas depend\u00eancias do embarcador ou do destinat\u00e1rio e o per\u00edodo gasto com a fiscaliza\u00e7\u00e3o da mercadoria transportada em barreiras fiscais ou alfandeg\u00e1rias, n\u00e3o sendo computados como jornada de trabalho e nem como horas extraordin\u00e1rias.<\/p>\n<p>\u00a7 9\u00ba As horas relativas ao tempo de espera ser\u00e3o indenizadas na propor\u00e7\u00e3o de 30% (trinta por cento) do sal\u00e1rio-hora normal.<\/p>\n<p>\u00a7 10\u00ba Em nenhuma hip\u00f3tese, o tempo de espera do motorista empregado prejudicar\u00e1 o direito ao recebimento da remunera\u00e7\u00e3o correspondente ao sal\u00e1rio-base di\u00e1rio.<\/p>\n<p>\u00a7 11\u00ba Quando a espera de que trata o \u00a7 8o for superior a 2 (duas) horas ininterruptas e for exigida a perman\u00eancia do motorista empregado junto ao ve\u00edculo, caso o local ofere\u00e7a condi\u00e7\u00f5es adequadas, o tempo ser\u00e1 considerado como de repouso para os fins do intervalo de que tratam os \u00a7\u00a7 2o e 3o, sem preju\u00edzo do disposto no \u00a7 9o.<\/p>\n<p>\u00a7 12\u00ba Durante o tempo de espera, o motorista poder\u00e1 realizar movimenta\u00e7\u00f5es necess\u00e1rias do ve\u00edculo, as quais n\u00e3o ser\u00e3o consideradas como parte da jornada de trabalho, ficando garantido, por\u00e9m, o gozo do descanso de 8 (oito) horas ininterruptas aludido no \u00a7 3o.<\/p>\n<p>\u00a7 13\u00ba Salvo previs\u00e3o contratual, a jornada de trabalho do motorista empregado n\u00e3o tem hor\u00e1rio fixo de in\u00edcio, de final ou de intervalos.<\/p>\n<p>\u00a7 14\u00ba O empregado \u00e9 respons\u00e1vel pela guarda, preserva\u00e7\u00e3o e exatid\u00e3o das informa\u00e7\u00f5es contidas nas anota\u00e7\u00f5es em di\u00e1rio de bordo, papeleta ou ficha de trabalho externo, ou no registrador instant\u00e2neo inalter\u00e1vel de velocidade e tempo, ou nos rastreadores ou sistemas e meios eletr\u00f4nicos, instalados nos ve\u00edculos, normatizados pelo Contran, at\u00e9 que o ve\u00edculo seja entregue \u00e0 empresa.<\/p>\n<p>\u00a7 15\u00ba Os dados referidos no \u00a7 14 poder\u00e3o ser enviados a dist\u00e2ncia, a crit\u00e9rio do empregador, facultando-se a anexa\u00e7\u00e3o do documento original posteriormente.<\/p>\n<p>\u00a7 16\u00ba Aplicam-se as disposi\u00e7\u00f5es deste artigo ao ajudante empregado nas opera\u00e7\u00f5es em que acompanhe o motorista.<\/p>\n<p>\u00a7 17\u00ba O disposto no caput deste artigo aplica-se tamb\u00e9m aos operadores de automotores destinados a puxar ou a arrastar maquinaria de qualquer natureza ou a executar trabalhos de constru\u00e7\u00e3o ou pavimenta\u00e7\u00e3o e aos operadores de tratores, colheitadeiras, autopropelidos e demais aparelhos automotores destinados a puxar ou a arrastar maquinaria agr\u00edcola ou a executar trabalhos agr\u00edcolas.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-D.<\/strong> Nas viagens de longa dist\u00e2ncia com dura\u00e7\u00e3o superior a 7 (sete) dias, o repouso semanal ser\u00e1 de 24 (vinte e quatro) horas por semana ou fra\u00e7\u00e3o trabalhada, sem preju\u00edzo do intervalo de repouso di\u00e1rio de 11 (onze) horas, totalizando 35 (trinta e cinco) horas, usufru\u00eddo no retorno do motorista \u00e0 base (matriz ou filial) ou ao seu domic\u00edlio, salvo se a empresa oferecer condi\u00e7\u00f5es adequadas para o efetivo gozo do referido repouso.<\/p>\n<p>I &#8211; revogado; (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015)<br \/>\nII &#8211; revogado; (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015)<br \/>\nIII &#8211; revogado. (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015)<\/p>\n<p>\u00a7 1\u00ba \u00c9 permitido o fracionamento do repouso semanal em 2 (dois) per\u00edodos, sendo um destes de, no m\u00ednimo, 30 (trinta) horas ininterruptas, a serem cumpridos na mesma semana e em continuidade a um per\u00edodo de repouso di\u00e1rio, que dever\u00e3o ser usufru\u00eddos no retorno da viagem.<\/p>\n<p>\u00a7 2\u00ba A cumulatividade de descansos semanais em viagens de longa dist\u00e2ncia de que trata o caput fica limitada ao n\u00famero de 3 (tr\u00eas) descansos consecutivos.<\/p>\n<p>\u00a7 3\u00ba O motorista empregado, em viagem de longa dist\u00e2ncia, que ficar com o ve\u00edculo parado ap\u00f3s o cumprimento da jornada normal ou das horas extraordin\u00e1rias fica dispensado do servi\u00e7o, exceto se for expressamente autorizada a sua perman\u00eancia junto ao ve\u00edculo pelo empregador, hip\u00f3tese em que o tempo ser\u00e1 considerado de espera.<\/p>\n<p>\u00a7 4\u00ba N\u00e3o ser\u00e1 considerado como jornada de trabalho, nem ensejar\u00e1 o pagamento de qualquer remunera\u00e7\u00e3o, o per\u00edodo em que o motorista empregado ou o ajudante ficarem espontaneamente no ve\u00edculo usufruindo dos intervalos de repouso.<\/p>\n<p>\u00a7 5\u00ba Nos casos em que o empregador adotar 2 (dois) motoristas trabalhando no mesmo ve\u00edculo, o tempo de repouso poder\u00e1 ser feito com o ve\u00edculo em movimento, assegurado o repouso m\u00ednimo de 6 (seis) horas consecutivas fora do ve\u00edculo em alojamento externo ou, se na cabine leito, com o ve\u00edculo estacionado, a cada 72 (setenta e duas) horas.<\/p>\n<p>\u00a7 6\u00ba Em situa\u00e7\u00f5es excepcionais de inobserv\u00e2ncia justificada do limite de jornada de que trata o art. 235-C, devidamente registradas, e desde que n\u00e3o se comprometa a seguran\u00e7a rodovi\u00e1ria, a dura\u00e7\u00e3o da jornada de trabalho do motorista profissional empregado poder\u00e1 ser elevada pelo tempo necess\u00e1rio at\u00e9 o ve\u00edculo chegar a um local seguro ou ao seu destino.<\/p>\n<p>\u00a7 7\u00ba Nos casos em que o motorista tenha que acompanhar o ve\u00edculo transportado por qualquer meio onde ele siga embarcado e em que o ve\u00edculo disponha de cabine leito ou a embarca\u00e7\u00e3o disponha de alojamento para gozo do intervalo de repouso di\u00e1rio previsto no \u00a7 3o do art. 235-C, esse tempo ser\u00e1 considerado como tempo de descanso.<\/p>\n<p>\u00a7 8\u00ba Para o transporte de cargas vivas, perec\u00edveis e especiais em longa dist\u00e2ncia ou em territ\u00f3rio estrangeiro poder\u00e3o ser aplicadas regras conforme a especificidade da opera\u00e7\u00e3o de transporte realizada, cujas condi\u00e7\u00f5es de trabalho ser\u00e3o fixadas em conven\u00e7\u00e3o ou acordo coletivo de modo a assegurar as adequadas condi\u00e7\u00f5es de viagem e entrega ao destino final.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-E.<\/strong> Para o transporte de passageiros, ser\u00e3o observados os seguintes dispositivos:<\/p>\n<p>I &#8211; \u00e9 facultado o fracionamento do intervalo de condu\u00e7\u00e3o do ve\u00edculo previsto na Lei no 9.503, de 23 de setembro de 1997 &#8211; C\u00f3digo de Tr\u00e2nsito Brasileiro, em per\u00edodos de no m\u00ednimo 5 (cinco) minutos;<br \/>\nII &#8211; ser\u00e1 assegurado ao motorista intervalo m\u00ednimo de 1 (uma) hora para refei\u00e7\u00e3o, podendo ser fracionado em 2 (dois) per\u00edodos e coincidir com o tempo de parada obrigat\u00f3ria na condu\u00e7\u00e3o do ve\u00edculo estabelecido pela Lei no 9.503, de 23 de setembro de 1997 &#8211; C\u00f3digo de Tr\u00e2nsito Brasileiro, exceto quando se tratar do motorista profissional enquadrado no \u00a7 5o do art. 71 desta Consolida\u00e7\u00e3o;<br \/>\nIII &#8211; nos casos em que o empregador adotar 2 (dois) motoristas no curso da mesma viagem, o descanso poder\u00e1 ser feito com o ve\u00edculo em movimento, respeitando-se os hor\u00e1rios de jornada de trabalho, assegurado, ap\u00f3s 72 (setenta e duas) horas, o repouso em alojamento externo ou, se em poltrona correspondente ao servi\u00e7o de leito, com o ve\u00edculo estacionado.<\/p>\n<p>\u00a7 1\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 2\u00ba (VETADO). (Inclu\u00edda pela Lei n\u00ba 12.619, de 2012) (Vig\u00eancia)<\/p>\n<p>\u00a7 3\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 4\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 5\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 6\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 7\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 8\u00ba (VETADO). (Inclu\u00edda pela Lei n\u00ba 12.619, de 2012) (Vig\u00eancia)<\/p>\n<p>\u00a7 9\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 10\u00ba (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 11. (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<p>\u00a7 12. (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015) (Vig\u00eancia)<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-F.<\/strong> Conven\u00e7\u00e3o e acordo coletivo poder\u00e3o prever jornada especial de 12 (doze) horas de trabalho por 36 (trinta e seis) horas de descanso para o trabalho do motorista profissional empregado em regime de compensa\u00e7\u00e3o.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-G.<\/strong> \u00c9 permitida a remunera\u00e7\u00e3o do motorista em fun\u00e7\u00e3o da dist\u00e2ncia percorrida, do tempo de viagem ou da natureza e quantidade de produtos transportados, inclusive mediante oferta de comiss\u00e3o ou qualquer outro tipo de vantagem, desde que essa remunera\u00e7\u00e3o ou comissionamento n\u00e3o comprometa a seguran\u00e7a da rodovia e da coletividade ou possibilite a viola\u00e7\u00e3o das normas previstas nesta Lei.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n\n<style>\n    .comment-block {\n        position: relative;\n    }\n    .comment-block .anchor-target {\n        position: absolute;\n        top: -200px;\n    }\n    .comment-block {\n        margin-bottom: 40px;\n    }\n    .comment-block .comment-block-title {\n        flex-wrap: wrap;\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 130%;\n        color: #1c1e2f;\n        margin-bottom: 24px;\n    }\n\n    .comment-block .comment-block-title:last-child {\n        margin-bottom: 64px;\n    }\n\n    .comment-block h3 {\n        font-size: 24px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .comment-block h4 {\n        font-size: 20px;\n        font-weight: 600;\n        line-height: 120%;\n    }\n\n    .article-box {\n        padding: 24px;\n        border-radius: 8px;\n        border: 1px solid #cbcbd9;\n        margin-bottom: 24px;\n    }\n\n    .article-box:last-child  {\n        margin-bottom: 0;\n    }\n\n    .article-box .article {\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        margin-bottom: 16px;\n    }\n\n    .article-box .article p {\n        margin-bottom: 1em;\n    }\n\n    .article-box .article p:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .article:last-child {\n        margin-bottom: 0;\n    }\n\n    .article-box .comment {\n        padding: 24px;\n        background-color: #f6f6fa;\n        font-size: 16px;\n        font-weight: 400;\n        line-height: 150%;\n        border-radius: 8px;\n    }\n\n    .article-box .comment p {\n        margin: 0;\n    }\n\n    .article-box .comment ol {\n        list-style: auto;\n        list-style-position: inside;\n    }\n\n    @media (max-width: 1199px) {\n        .comment-block .comment-block-title {\n            font-size: 16px;\n        }\n\n        .comment-block .comment-block-title h2 {\n            margin-right: 5px;\n        }\n\n        .comment-block h3 {\n            font-size: 20px;\n        }\n        .comment-block h4 {\n            font-size: 18px;\n        }\n    }\n<\/style>\n\n<div class=\"comment-block cp-block\">\n    <!-- Chama a ancora e\/ou titulo se houver -->\n        \n    <!-- Bloco de comentario -->\n            <div class=\"article-box\">\n            <div class=\"article\"><p><strong>Art. 235-H.<\/strong> (Revogado). (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.103, de 2015)<\/p>\n<\/div>\n                    <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","cat-clt":[540,539],"class_list":["post-28412","clt-comentado","type-clt-comentado","status-publish","hentry","cat-clt-capitulo-i-titulo-iii-2","cat-clt-titulo-iii"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/clt-comentado\/28412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/clt-comentado"}],"about":[{"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/types\/clt-comentado"}],"author":[{"embeddable":true,"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/comments?post=28412"}],"wp:attachment":[{"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/media?parent=28412"}],"wp:term":[{"taxonomy":"cat-clt","embeddable":true,"href":"https:\/\/www.aurum.com.br\/blog\/wp-json\/wp\/v2\/cat-clt?post=28412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}